{"id":1132,"date":"2022-09-19T14:35:52","date_gmt":"2022-09-19T14:35:52","guid":{"rendered":"https:\/\/zvapfier.gov.al\/?p=1132"},"modified":"2022-09-19T14:35:52","modified_gmt":"2022-09-19T14:35:52","slug":"levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022","status":"publish","type":"post","link":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/","title":{"rendered":"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;<\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-decb7d79-30a4-4d31-8910-a27aef2c8602\" href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2022\/09\/LEVIZJET-PARALELE-TE-REALIZUARA-DERI-08.09.2022.pdf\">LEVIZJET-PARALELE-TE-REALIZUARA-DERI-08.09.2022<\/a><a href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2022\/09\/LEVIZJET-PARALELE-TE-REALIZUARA-DERI-08.09.2022.pdf\" class=\"wp-block-file__button\" download aria-describedby=\"wp-block-file--media-decb7d79-30a4-4d31-8910-a27aef2c8602\">Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1132","post","type-post","status-publish","format-standard","hentry","category-pakategori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a0&quot;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&quot; - ZVAP FIER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a0&quot;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&quot; - ZVAP FIER\" \/>\n<meta property=\"og:description\" content=\"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"ZVAP FIER\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-19T14:35:52+00:00\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"headline\":\"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;\",\"datePublished\":\"2022-09-19T14:35:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/\"},\"wordCount\":20,\"commentCount\":0,\"articleSection\":[\"Pakategori\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/\",\"name\":\"\u00a0\\\"L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022\\\" - ZVAP FIER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\"},\"datePublished\":\"2022-09-19T14:35:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2022\\\/09\\\/19\\\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zvapfier.gov.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/\",\"name\":\"ZVAP FIER\",\"description\":\"Zyra Vendore Arsimore Parauniversitare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zvapfier.gov.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\",\"name\":\"user\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a0\"L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022\" - ZVAP FIER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/","og_locale":"en_US","og_type":"article","og_title":"\u00a0\"L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022\" - ZVAP FIER","og_description":"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;","og_url":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/","og_site_name":"ZVAP FIER","article_published_time":"2022-09-19T14:35:52+00:00","author":"user","twitter_card":"summary_large_image","twitter_misc":{"Written by":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/#article","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/"},"author":{"name":"user","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"headline":"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;","datePublished":"2022-09-19T14:35:52+00:00","mainEntityOfPage":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/"},"wordCount":20,"commentCount":0,"articleSection":["Pakategori"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/","url":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/","name":"\u00a0\"L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022\" - ZVAP FIER","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/#website"},"datePublished":"2022-09-19T14:35:52+00:00","author":{"@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"breadcrumb":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zvapfier.gov.al\/index.php\/2022\/09\/19\/levizjet-paralele-te-realizuara-deri-ne-daten-08-09-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zvapfier.gov.al\/"},{"@type":"ListItem","position":2,"name":"\u00a0&#8220;L\u00ebvizjet paralele t\u00eb realizuara deri n\u00eb dat\u00ebn 08.09.2022&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/zvapfier.gov.al\/#website","url":"https:\/\/zvapfier.gov.al\/","name":"ZVAP FIER","description":"Zyra Vendore Arsimore Parauniversitare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zvapfier.gov.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c","name":"user","url":"https:\/\/zvapfier.gov.al\/index.php\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/comments?post=1132"}],"version-history":[{"count":1,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1132\/revisions"}],"predecessor-version":[{"id":1134,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1132\/revisions\/1134"}],"wp:attachment":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/media?parent=1132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/categories?post=1132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/tags?post=1132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}