{"id":1347,"date":"2023-02-27T13:32:23","date_gmt":"2023-02-27T13:32:23","guid":{"rendered":"https:\/\/zvapfier.gov.al\/?p=1347"},"modified":"2023-02-27T13:32:23","modified_gmt":"2023-02-27T13:32:23","slug":"mbi-aplikimet-a1-a1z-msh-2023","status":"publish","type":"post","link":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/","title":{"rendered":"Mbi Aplikimet A1\/A1Z MSH 2023"},"content":{"rendered":"\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-7cea44e8-d4ce-4e08-97a6-70c1263a236e\" href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2023\/02\/Urdher-Nr12-.-Dt-22.02.2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Urdher-Nr12-.-Dt-22.02.2023<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"Urdher-Nr12-.-Dt-22.02.2023","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1347","post","type-post","status-publish","format-standard","hentry","category-pakategori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mbi Aplikimet A1\/A1Z MSH 2023 - ZVAP FIER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mbi Aplikimet A1\/A1Z MSH 2023 - ZVAP FIER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"ZVAP FIER\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-27T13:32:23+00:00\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"headline\":\"Mbi Aplikimet A1\\\/A1Z MSH 2023\",\"datePublished\":\"2023-02-27T13:32:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/\"},\"wordCount\":9,\"commentCount\":0,\"articleSection\":[\"Pakategori\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/\",\"name\":\"Mbi Aplikimet A1\\\/A1Z MSH 2023 - ZVAP FIER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\"},\"datePublished\":\"2023-02-27T13:32:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/02\\\/27\\\/mbi-aplikimet-a1-a1z-msh-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zvapfier.gov.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mbi Aplikimet A1\\\/A1Z MSH 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/\",\"name\":\"ZVAP FIER\",\"description\":\"Zyra Vendore Arsimore Parauniversitare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zvapfier.gov.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\",\"name\":\"user\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mbi Aplikimet A1\/A1Z MSH 2023 - ZVAP FIER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/","og_locale":"en_US","og_type":"article","og_title":"Mbi Aplikimet A1\/A1Z MSH 2023 - ZVAP FIER","og_url":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/","og_site_name":"ZVAP FIER","article_published_time":"2023-02-27T13:32:23+00:00","author":"user","twitter_card":"summary_large_image","twitter_misc":{"Written by":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/#article","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/"},"author":{"name":"user","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"headline":"Mbi Aplikimet A1\/A1Z MSH 2023","datePublished":"2023-02-27T13:32:23+00:00","mainEntityOfPage":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/"},"wordCount":9,"commentCount":0,"articleSection":["Pakategori"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/","url":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/","name":"Mbi Aplikimet A1\/A1Z MSH 2023 - ZVAP FIER","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/#website"},"datePublished":"2023-02-27T13:32:23+00:00","author":{"@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"breadcrumb":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/02\/27\/mbi-aplikimet-a1-a1z-msh-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zvapfier.gov.al\/"},{"@type":"ListItem","position":2,"name":"Mbi Aplikimet A1\/A1Z MSH 2023"}]},{"@type":"WebSite","@id":"https:\/\/zvapfier.gov.al\/#website","url":"https:\/\/zvapfier.gov.al\/","name":"ZVAP FIER","description":"Zyra Vendore Arsimore Parauniversitare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zvapfier.gov.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c","name":"user","url":"https:\/\/zvapfier.gov.al\/index.php\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/comments?post=1347"}],"version-history":[{"count":1,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1347\/revisions"}],"predecessor-version":[{"id":1349,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1347\/revisions\/1349"}],"wp:attachment":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/media?parent=1347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/categories?post=1347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/tags?post=1347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}