{"id":1476,"date":"2023-08-25T15:46:34","date_gmt":"2023-08-25T15:46:34","guid":{"rendered":"https:\/\/zvapfier.gov.al\/?p=1476"},"modified":"2023-08-25T15:46:34","modified_gmt":"2023-08-25T15:46:34","slug":"rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar","status":"publish","type":"post","link":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/","title":{"rendered":"Rezultatet paraprake levizje paralele dhe paralele e detyruar."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">N\u00eb mb\u00ebshtetje t\u00eb Ligjit 69\/2012 \u2018\u2019P\u00ebr sistemin arsimor parauniversitar n\u00eb Republik\u00ebn e Shqip\u00ebris\u00eb\u2019\u2019, i ndryshuar, Kodin e Pun\u00ebs s\u00eb Republik\u00ebs s\u00eb Shqip\u00ebris\u00eb, i ndryshuar,\u00a0 \u00a0Vendimit nr.99, dat\u00eb 27.02.2019 t\u00eb K\u00ebshillit t\u00eb Ministrave , \u2018\u2019P\u00ebr krijimin, m\u00ebnyr\u00ebn e organizimit dhe t\u00eb funksionimit t\u00eb Drejtoris\u00eb s\u00eb P\u00ebrgjithshme t\u00eb Arsimit Parauniversitar\u2019\u2019,\u00a0udh\u00ebzimin nr.12, dat\u00eb 10.06.2021, \u2018\u2019P\u00ebr procedurat e pranimit dhe t\u00eb em\u00ebrimit t\u00eb m\u00ebsuesit n\u00eb nj\u00eb vend t\u00eb lir\u00eb pune n\u00eb institucionet arsimore dhe p\u00ebr administrimin e portalit \u2018\u2019M\u00ebsues p\u00ebr Shqip\u00ebrin\u00eb\u2019\u2019, i ndryshuar,\u00a0udh\u00ebzimit nr.14, dat\u00eb 10.07.2023, \u2018\u2019P\u00ebr numrin e nx\u00ebn\u00ebsve p\u00ebr klas\u00eb dhe ngarkes\u00ebn m\u00ebsimore t\u00eb punonj\u00ebsve arsimor n\u00eb institucionet e arsimit parauniversitar\u2019 bashk\u00ebngjitur rezultatet paraprake l\u00ebvizje paralele dhe paralele e detyruar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kandidatet te cilet pretendojne per vleresim jo te drejte nga KVD e ZVAP Fier jane te lutur te paraqesin ankese<strong>\u00a0ne sekretarine e institucionit brenda 3 diteve<\/strong>, afat i cili fillon qe nga dita e neserme e publikimit.<\/p>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-c0e3c126-c4de-4024-99ed-db3601674d10\" href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2023\/08\/Rezultatet-paraprake-per-levizjen-me-detyrim_1.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Rezultatet-paraprake-per-levizjen-me-detyrim_1<\/a><\/div>\n\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-6be680c6-1bc7-438b-ab92-0fda80ae6ae9\" href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2023\/08\/Rezultatet-paraprake-per-levizjen-me-deshire.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Rezultatet-paraprake-per-levizjen-me-deshire<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>N\u00eb mb\u00ebshtetje t\u00eb Ligjit 69\/2012 \u2018\u2019P\u00ebr sistemin arsimor parauniversitar n\u00eb Republik\u00ebn e Shqip\u00ebris\u00eb\u2019\u2019, i ndryshuar, Kodin e Pun\u00ebs s\u00eb Republik\u00ebs s\u00eb Shqip\u00ebris\u00eb, i ndryshuar,\u00a0 \u00a0Vendimit nr.99, dat\u00eb 27.02.2019 t\u00eb K\u00ebshillit t\u00eb Ministrave&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1476","post","type-post","status-publish","format-standard","hentry","category-njoftime"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER\" \/>\n<meta property=\"og:description\" content=\"N\u00eb mb\u00ebshtetje t\u00eb Ligjit 69\/2012 \u2018\u2019P\u00ebr sistemin arsimor parauniversitar n\u00eb Republik\u00ebn e Shqip\u00ebris\u00eb\u2019\u2019, i ndryshuar, Kodin e Pun\u00ebs s\u00eb Republik\u00ebs s\u00eb Shqip\u00ebris\u00eb, i ndryshuar,\u00a0 \u00a0Vendimit nr.99, dat\u00eb 27.02.2019 t\u00eb K\u00ebshillit t\u00eb Ministrave...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/\" \/>\n<meta property=\"og:site_name\" content=\"ZVAP FIER\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-25T15:46:34+00:00\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"headline\":\"Rezultatet paraprake levizje paralele dhe paralele e detyruar.\",\"datePublished\":\"2023-08-25T15:46:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/\"},\"wordCount\":182,\"commentCount\":0,\"articleSection\":[\"Njoftime\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/\",\"name\":\"Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\"},\"datePublished\":\"2023-08-25T15:46:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2023\\\/08\\\/25\\\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zvapfier.gov.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rezultatet paraprake levizje paralele dhe paralele e detyruar.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/\",\"name\":\"ZVAP FIER\",\"description\":\"Zyra Vendore Arsimore Parauniversitare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zvapfier.gov.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\",\"name\":\"user\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/","og_locale":"en_US","og_type":"article","og_title":"Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER","og_description":"N\u00eb mb\u00ebshtetje t\u00eb Ligjit 69\/2012 \u2018\u2019P\u00ebr sistemin arsimor parauniversitar n\u00eb Republik\u00ebn e Shqip\u00ebris\u00eb\u2019\u2019, i ndryshuar, Kodin e Pun\u00ebs s\u00eb Republik\u00ebs s\u00eb Shqip\u00ebris\u00eb, i ndryshuar,\u00a0 \u00a0Vendimit nr.99, dat\u00eb 27.02.2019 t\u00eb K\u00ebshillit t\u00eb Ministrave...","og_url":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/","og_site_name":"ZVAP FIER","article_published_time":"2023-08-25T15:46:34+00:00","author":"user","twitter_card":"summary_large_image","twitter_misc":{"Written by":"user","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/#article","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/"},"author":{"name":"user","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"headline":"Rezultatet paraprake levizje paralele dhe paralele e detyruar.","datePublished":"2023-08-25T15:46:34+00:00","mainEntityOfPage":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/"},"wordCount":182,"commentCount":0,"articleSection":["Njoftime"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/","url":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/","name":"Rezultatet paraprake levizje paralele dhe paralele e detyruar. - ZVAP FIER","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/#website"},"datePublished":"2023-08-25T15:46:34+00:00","author":{"@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"breadcrumb":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zvapfier.gov.al\/index.php\/2023\/08\/25\/rezultatet-paraprake-levizje-paralele-dhe-paralele-e-detyruar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zvapfier.gov.al\/"},{"@type":"ListItem","position":2,"name":"Rezultatet paraprake levizje paralele dhe paralele e detyruar."}]},{"@type":"WebSite","@id":"https:\/\/zvapfier.gov.al\/#website","url":"https:\/\/zvapfier.gov.al\/","name":"ZVAP FIER","description":"Zyra Vendore Arsimore Parauniversitare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zvapfier.gov.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c","name":"user","url":"https:\/\/zvapfier.gov.al\/index.php\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/comments?post=1476"}],"version-history":[{"count":1,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1476\/revisions"}],"predecessor-version":[{"id":1479,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1476\/revisions\/1479"}],"wp:attachment":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/media?parent=1476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/categories?post=1476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/tags?post=1476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}