{"id":1764,"date":"2024-02-01T10:21:43","date_gmt":"2024-02-01T10:21:43","guid":{"rendered":"https:\/\/zvapfier.gov.al\/?p=1764"},"modified":"2024-02-01T10:21:43","modified_gmt":"2024-02-01T10:21:43","slug":"kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024","status":"publish","type":"post","link":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/","title":{"rendered":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024"},"content":{"rendered":"\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2024\/02\/Doc-01-30-2024-15-12-36-1-1.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of Doc-01-30-2024-15-12-36-1-1.\"><\/object><a id=\"wp-block-file--media-a6d56670-dbb0-44fb-821d-6f517cf504d2\" href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2024\/02\/Doc-01-30-2024-15-12-36-1-1.pdf\">Doc-01-30-2024-15-12-36-1-1<\/a><a href=\"https:\/\/zvapfier.gov.al\/wp-content\/uploads\/2024\/02\/Doc-01-30-2024-15-12-36-1-1.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-a6d56670-dbb0-44fb-821d-6f517cf504d2\">Download<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"Doc-01-30-2024-15-12-36-1-1Download","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1764","post","type-post","status-publish","format-standard","hentry","category-pakategori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"ZVAP FIER\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-01T10:21:43+00:00\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"user\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/\"},\"author\":{\"name\":\"user\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"headline\":\"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024\",\"datePublished\":\"2024-02-01T10:21:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/\"},\"wordCount\":18,\"commentCount\":0,\"articleSection\":[\"Pakategori\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/\",\"name\":\"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\"},\"datePublished\":\"2024-02-01T10:21:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/2024\\\/02\\\/01\\\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zvapfier.gov.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#website\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/\",\"name\":\"ZVAP FIER\",\"description\":\"Zyra Vendore Arsimore Parauniversitare\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zvapfier.gov.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zvapfier.gov.al\\\/#\\\/schema\\\/person\\\/00cda588815b1e244e3bdb4fb5b2038c\",\"name\":\"user\",\"url\":\"https:\\\/\\\/zvapfier.gov.al\\\/index.php\\\/author\\\/user\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/","og_locale":"en_US","og_type":"article","og_title":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER","og_url":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/","og_site_name":"ZVAP FIER","article_published_time":"2024-02-01T10:21:43+00:00","author":"user","twitter_card":"summary_large_image","twitter_misc":{"Written by":"user"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/#article","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/"},"author":{"name":"user","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"headline":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024","datePublished":"2024-02-01T10:21:43+00:00","mainEntityOfPage":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/"},"wordCount":18,"commentCount":0,"articleSection":["Pakategori"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/","url":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/","name":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024 - ZVAP FIER","isPartOf":{"@id":"https:\/\/zvapfier.gov.al\/#website"},"datePublished":"2024-02-01T10:21:43+00:00","author":{"@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c"},"breadcrumb":{"@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zvapfier.gov.al\/index.php\/2024\/02\/01\/kualifikimi-i-mesuesve-per-vitin-shkollor-2023-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zvapfier.gov.al\/"},{"@type":"ListItem","position":2,"name":"Kualifikimi i m\u00ebsuesve p\u00ebr vitin shkollor 2023-2024"}]},{"@type":"WebSite","@id":"https:\/\/zvapfier.gov.al\/#website","url":"https:\/\/zvapfier.gov.al\/","name":"ZVAP FIER","description":"Zyra Vendore Arsimore Parauniversitare","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zvapfier.gov.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/zvapfier.gov.al\/#\/schema\/person\/00cda588815b1e244e3bdb4fb5b2038c","name":"user","url":"https:\/\/zvapfier.gov.al\/index.php\/author\/user\/"}]}},"_links":{"self":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":1,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"predecessor-version":[{"id":1766,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/posts\/1764\/revisions\/1766"}],"wp:attachment":[{"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zvapfier.gov.al\/index.php\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}